{"id":27999,"date":"2026-07-10T12:30:25","date_gmt":"2026-07-10T11:30:25","guid":{"rendered":"https:\/\/pintrip.eu\/de\/?p=27999"},"modified":"2026-07-10T12:30:25","modified_gmt":"2026-07-10T11:30:25","slug":"rosenhaven","status":"publish","type":"post","link":"https:\/\/pintrip.eu\/de\/rosenhaven\/","title":{"rendered":"Rosenhaven"},"content":{"rendered":"<p data-start=\"0\" data-end=\"151\">Wir haben den Ort besucht und den sehr sch\u00f6nen Garten besichtigt. Mit sehr viel Liebe angelegt und eine Empfehlung f\u00fcr Rosenliebhaber. Danke f\u00fcr die kleine F\u00fchrung durch den Garten. Gerne wieder<\/p>\n<p><em>Walter Wurzinger<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir haben den Ort besucht und den sehr sch\u00f6nen Garten besichtigt. Mit sehr viel Liebe angelegt und eine Empfehlung f\u00fcr Rosenliebhaber. Danke f\u00fcr die kleine F\u00fchrung durch den Garten. Gerne wieder Walter Wurzinger<\/p>\n","protected":false},"author":4,"featured_media":28000,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[50],"tags":[],"class_list":["post-27999","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gaeste-erzaehlen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rosenhaven<\/title>\n<meta name=\"description\" content=\"Wir haben den Ort besucht und den sehr sch\u00f6nen Garten besichtigt. Mit sehr viel Liebe angelegt und eine Empfehlung f\u00fcr Rosenliebhaber. Danke f\u00fcr die kleine F\u00fchrung durch den Garten. Gerne wieder Walter Wurzinger\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pintrip.eu\/de\/rosenhaven\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rosenhaven\" \/>\n<meta property=\"og:description\" content=\"Wir haben den Ort besucht und den sehr sch\u00f6nen Garten besichtigt. Mit sehr viel Liebe angelegt und eine Empfehlung f\u00fcr Rosenliebhaber. Danke f\u00fcr die kleine F\u00fchrung durch den Garten. Gerne wieder Walter Wurzinger\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pintrip.eu\/de\/rosenhaven\/\" \/>\n<meta property=\"og:site_name\" content=\"pintrip.eu\/de\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-10T11:30:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pintrip.eu\/de\/wp-content\/uploads\/sites\/8\/2026\/07\/2061_Rosenhaven_2019_4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Henriette - Pintrip\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Henriette - Pintrip\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/rosenhaven\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/rosenhaven\\\/\"},\"author\":{\"name\":\"Henriette - Pintrip\",\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/#\\\/schema\\\/person\\\/784b9d12953c006071a98024f5ae29a5\"},\"headline\":\"Rosenhaven\",\"datePublished\":\"2026-07-10T11:30:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/rosenhaven\\\/\"},\"wordCount\":38,\"image\":{\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/rosenhaven\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2026\\\/07\\\/2061_Rosenhaven_2019_4.jpg\",\"articleSection\":[\"G\u00e4ste erz\u00e4hlen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/rosenhaven\\\/\",\"url\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/rosenhaven\\\/\",\"name\":\"Rosenhaven\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/rosenhaven\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/rosenhaven\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2026\\\/07\\\/2061_Rosenhaven_2019_4.jpg\",\"datePublished\":\"2026-07-10T11:30:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/#\\\/schema\\\/person\\\/784b9d12953c006071a98024f5ae29a5\"},\"description\":\"Wir haben den Ort besucht und den sehr sch\u00f6nen Garten besichtigt. Mit sehr viel Liebe angelegt und eine Empfehlung f\u00fcr Rosenliebhaber. Danke f\u00fcr die kleine F\u00fchrung durch den Garten. Gerne wieder Walter Wurzinger\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/rosenhaven\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pintrip.eu\\\/de\\\/rosenhaven\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/rosenhaven\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2026\\\/07\\\/2061_Rosenhaven_2019_4.jpg\",\"contentUrl\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2026\\\/07\\\/2061_Rosenhaven_2019_4.jpg\",\"width\":640,\"height\":480,\"caption\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/rosenhaven\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rosenhaven\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/\",\"name\":\"pintrip.eu\\\/de\",\"description\":\"a way of living\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/#\\\/schema\\\/person\\\/784b9d12953c006071a98024f5ae29a5\",\"name\":\"Henriette - Pintrip\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/886176521270c62c5f3ea099223aa87dd8724f2e18252a9b2a3440e95780721e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/886176521270c62c5f3ea099223aa87dd8724f2e18252a9b2a3440e95780721e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/886176521270c62c5f3ea099223aa87dd8724f2e18252a9b2a3440e95780721e?s=96&d=mm&r=g\",\"caption\":\"Henriette - Pintrip\"},\"sameAs\":[\"https:\\\/\\\/pintrip.eu\"],\"url\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/author\\\/pintrip\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rosenhaven","description":"Wir haben den Ort besucht und den sehr sch\u00f6nen Garten besichtigt. Mit sehr viel Liebe angelegt und eine Empfehlung f\u00fcr Rosenliebhaber. Danke f\u00fcr die kleine F\u00fchrung durch den Garten. Gerne wieder Walter Wurzinger","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pintrip.eu\/de\/rosenhaven\/","og_locale":"de_DE","og_type":"article","og_title":"Rosenhaven","og_description":"Wir haben den Ort besucht und den sehr sch\u00f6nen Garten besichtigt. Mit sehr viel Liebe angelegt und eine Empfehlung f\u00fcr Rosenliebhaber. Danke f\u00fcr die kleine F\u00fchrung durch den Garten. Gerne wieder Walter Wurzinger","og_url":"https:\/\/pintrip.eu\/de\/rosenhaven\/","og_site_name":"pintrip.eu\/de","article_published_time":"2026-07-10T11:30:25+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/pintrip.eu\/de\/wp-content\/uploads\/sites\/8\/2026\/07\/2061_Rosenhaven_2019_4.jpg","type":"image\/jpeg"}],"author":"Henriette - Pintrip","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Henriette - Pintrip","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pintrip.eu\/de\/rosenhaven\/#article","isPartOf":{"@id":"https:\/\/pintrip.eu\/de\/rosenhaven\/"},"author":{"name":"Henriette - Pintrip","@id":"https:\/\/pintrip.eu\/de\/#\/schema\/person\/784b9d12953c006071a98024f5ae29a5"},"headline":"Rosenhaven","datePublished":"2026-07-10T11:30:25+00:00","mainEntityOfPage":{"@id":"https:\/\/pintrip.eu\/de\/rosenhaven\/"},"wordCount":38,"image":{"@id":"https:\/\/pintrip.eu\/de\/rosenhaven\/#primaryimage"},"thumbnailUrl":"https:\/\/pintrip.eu\/de\/wp-content\/uploads\/sites\/8\/2026\/07\/2061_Rosenhaven_2019_4.jpg","articleSection":["G\u00e4ste erz\u00e4hlen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/pintrip.eu\/de\/rosenhaven\/","url":"https:\/\/pintrip.eu\/de\/rosenhaven\/","name":"Rosenhaven","isPartOf":{"@id":"https:\/\/pintrip.eu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pintrip.eu\/de\/rosenhaven\/#primaryimage"},"image":{"@id":"https:\/\/pintrip.eu\/de\/rosenhaven\/#primaryimage"},"thumbnailUrl":"https:\/\/pintrip.eu\/de\/wp-content\/uploads\/sites\/8\/2026\/07\/2061_Rosenhaven_2019_4.jpg","datePublished":"2026-07-10T11:30:25+00:00","author":{"@id":"https:\/\/pintrip.eu\/de\/#\/schema\/person\/784b9d12953c006071a98024f5ae29a5"},"description":"Wir haben den Ort besucht und den sehr sch\u00f6nen Garten besichtigt. Mit sehr viel Liebe angelegt und eine Empfehlung f\u00fcr Rosenliebhaber. Danke f\u00fcr die kleine F\u00fchrung durch den Garten. Gerne wieder Walter Wurzinger","breadcrumb":{"@id":"https:\/\/pintrip.eu\/de\/rosenhaven\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pintrip.eu\/de\/rosenhaven\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/pintrip.eu\/de\/rosenhaven\/#primaryimage","url":"https:\/\/pintrip.eu\/de\/wp-content\/uploads\/sites\/8\/2026\/07\/2061_Rosenhaven_2019_4.jpg","contentUrl":"https:\/\/pintrip.eu\/de\/wp-content\/uploads\/sites\/8\/2026\/07\/2061_Rosenhaven_2019_4.jpg","width":640,"height":480,"caption":""},{"@type":"BreadcrumbList","@id":"https:\/\/pintrip.eu\/de\/rosenhaven\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/pintrip.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Rosenhaven"}]},{"@type":"WebSite","@id":"https:\/\/pintrip.eu\/de\/#website","url":"https:\/\/pintrip.eu\/de\/","name":"pintrip.eu\/de","description":"a way of living","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pintrip.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/pintrip.eu\/de\/#\/schema\/person\/784b9d12953c006071a98024f5ae29a5","name":"Henriette - Pintrip","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/886176521270c62c5f3ea099223aa87dd8724f2e18252a9b2a3440e95780721e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/886176521270c62c5f3ea099223aa87dd8724f2e18252a9b2a3440e95780721e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/886176521270c62c5f3ea099223aa87dd8724f2e18252a9b2a3440e95780721e?s=96&d=mm&r=g","caption":"Henriette - Pintrip"},"sameAs":["https:\/\/pintrip.eu"],"url":"https:\/\/pintrip.eu\/de\/author\/pintrip\/"}]}},"_links":{"self":[{"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/posts\/27999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/comments?post=27999"}],"version-history":[{"count":1,"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/posts\/27999\/revisions"}],"predecessor-version":[{"id":28001,"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/posts\/27999\/revisions\/28001"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/media\/28000"}],"wp:attachment":[{"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/media?parent=27999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/categories?post=27999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/tags?post=27999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}