{"id":18720,"date":"2022-05-16T11:13:39","date_gmt":"2022-05-16T10:13:39","guid":{"rendered":"https:\/\/pintrip.eu\/de\/?p=18720"},"modified":"2022-05-16T11:13:44","modified_gmt":"2022-05-16T10:13:44","slug":"ihr-hund-ist-willkommen","status":"publish","type":"post","link":"https:\/\/pintrip.eu\/de\/ihr-hund-ist-willkommen\/","title":{"rendered":"Ihr Hund ist willkommen"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;3.22&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row admin_label=&#8221;row&#8221; _builder_version=&#8221;3.25&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.14.8&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p><strong>Ihr Hund ist willkommen<\/strong><\/p>\n<p>Bei \u00fcber 90 % unserer Gastgeber ist auch Ihr Hund willkommen. Das Symbol mit dem Hund auf der Gastgeberseite zeigt, dass HIER Ihr Hund willkommen ist. Bei einigen Gastgebern k\u00f6nnen Sie Ihren Hund nicht mitbringen, und das kann mehrere Gr\u00fcnde haben. Vielleicht hat der Gastgeber einen eigenen Hund oder er hat Tiere, die stark auf andere Hunde reagieren, wie zum Beispiel Schafe. Wenn das Symbol mit dem Hund nicht auf der Gastgeber Seite ist, k\u00f6nnen Sie den Ort nicht besuchen, wenn Sie mit einem Hund reisen, auch wenn Sie ihn w\u00e4hrend Ihres Aufenthalts im Wohnmobil behalten.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ihr Hund ist willkommen Bei \u00fcber 90 % unserer Gastgeber ist auch Ihr Hund willkommen. Das Symbol mit dem Hund auf der Gastgeberseite zeigt, dass HIER Ihr Hund willkommen ist. Bei einigen Gastgebern k\u00f6nnen Sie Ihren Hund nicht mitbringen, und das kann mehrere Gr\u00fcnde haben. Vielleicht hat der Gastgeber einen eigenen Hund oder er hat [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":18721,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<strong>Die Leute dahinter Pintrip\r\n<\/strong>Wenn Sie 2018 von Anfang an dabei waren, brauchen wir Ihnen wahrscheinlich nicht die gro\u00dfe Pr\u00e4sentation zu machen. Aber wenn Sie seitdem in diesem Universum angekommen sind, sind Sie sich vielleicht nicht ganz sicher, wer wir sind. Die Idee zu Pintrip begann im Sp\u00e4tsommer 2018 und seitdem hat sich viel im Unternehmen getan. Denn ja Pintrip ist ein Unternehmen, keine freiwillige Organisation. Deshalb arbeiten wir nicht gemeinn\u00fctzig. In kurzer Zeit ist viel passiert, daher ist es an der Zeit, uns m\u00f6chten uns kurz bei Ihren vorstellen.\r\n\r\n<strong>Henriette Rask\r\n<\/strong>Inhaber und Gesch\u00e4ftsf\u00fchrer von Pintrip. Im Herbst 2018 verabschiedete sie sich von ihrem Job als Arzthelferin, um sich der Gr\u00fcndungsphase von Pintrip zu widmen \u2013 die sich als zeitaufwendiger herausstellte als gedacht. Henriette ist f\u00fcr das Tagesgesch\u00e4ft von Pintrip verantwortlich und hat verschiedene Funktionen. Wenn Sie also Pintrip anrufen oder schreiben, wird sie antworten. Henriette bleibt mit allen Pintrip-Gastgebern in Kontakt und wei\u00df immer, was im Pintrip-Universum und in der Reisemobilwelt los ist. Au\u00dferdem k\u00fcmmert sie sich um die t\u00e4gliche administrative Arbeit und schreibt gemeinsam mit Nicoline den monatlichen Newsletter und sie liest den Pintrip Guide Korrektur.\r\n\r\n<strong>Peter Rask\r\n<\/strong>Peter ist mit Henriette verheiratet (\u00dcberraschung!). Er ist ein wichtiger Teil des Alltags bei Pintrip, denn er ist ein wichtiger Sparringspartner und der Verpackungsmeister des Unternehmens. Unter anderem ist es Peter, der dir einen Pintrip-Guide gepackt und geschickt hat. Er sorgt daf\u00fcr, dass all die tausenden Pintrip-F\u00fchrer mit Vignetten, Mitgliedskarten und diversen Zusatzbrosch\u00fcren ordentlich verpackt sind. Es erfordert viel Genauigkeit, die Peter bis zur Perfektion beherrscht. Peter hat auch einen Vollzeitjob als Sozialp\u00e4dagoge.\r\n\r\n<strong>Nicoline Hoelgaard\r\n<\/strong>Kommunikationsbeauftragter, der fast seit dem Start von Pintrip bei uns ist. Begonnen hat es mit einem Praktikum im M\u00e4rz 2019, aus dem zun\u00e4chst eine Teilzeitbesch\u00e4ftigung und sp\u00e4ter eine Vollzeitstellebesch\u00e4ftigung wurde. Aufgrund der Corona-Situation ist es nochmals eine Teilzeitbesch\u00e4ftigung. Sie ist f\u00fcr SoMe verantwortlich, und sie erstellt Social Media Inhalten.\r\n\r\nAu\u00dferdem schreibt sie mit Henriette den monatlichen Newsletter und \u00fcbersetzt ihn anschlie\u00dfend ins Englische und Deutsche. Nicoline ist besonders in den Wintermonaten besch\u00e4ftigt, da sie die Hostseiten f\u00fcr den Pintrip Guide schreibt und diese ins Englische und Deutsche \u00fcbersetzt. Nicoline hat auch einen Teilzeitjob als Verk\u00e4uferin.","_et_gb_content_width":"","footnotes":""},"categories":[64],"tags":[],"class_list":["post-18720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ihr Hund ist willkommen<\/title>\n<meta name=\"description\" content=\"Bei \u00fcber 90 % unserer Gastgeber ist auch Ihr Hund willkommen. Das Symbol mit dem Hund auf der Gastgeberseite zeigt, dass HIER Ihr Hund willkommen ist. Bei einigen\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pintrip.eu\/de\/ihr-hund-ist-willkommen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ihr Hund ist willkommen\" \/>\n<meta property=\"og:description\" content=\"Bei \u00fcber 90 % unserer Gastgeber ist auch Ihr Hund willkommen. Das Symbol mit dem Hund auf der Gastgeberseite zeigt, dass HIER Ihr Hund willkommen ist. Bei einigen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pintrip.eu\/de\/ihr-hund-ist-willkommen\/\" \/>\n<meta property=\"og:site_name\" content=\"pintrip.eu\/de\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-16T10:13:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-16T10:13:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pintrip.eu\/de\/wp-content\/uploads\/sites\/8\/2022\/05\/Pintrip_2021_11-scaled-e1652695943120.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"967\" \/>\n\t<meta property=\"og:image:height\" content=\"990\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Henriette - Pintrip\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Henriette - Pintrip\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/ihr-hund-ist-willkommen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/ihr-hund-ist-willkommen\\\/\"},\"author\":{\"name\":\"Henriette - Pintrip\",\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/#\\\/schema\\\/person\\\/784b9d12953c006071a98024f5ae29a5\"},\"headline\":\"Ihr Hund ist willkommen\",\"datePublished\":\"2022-05-16T10:13:39+00:00\",\"dateModified\":\"2022-05-16T10:13:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/ihr-hund-ist-willkommen\\\/\"},\"wordCount\":191,\"image\":{\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/ihr-hund-ist-willkommen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/05\\\/Pintrip_2021_11-scaled-e1652695943120.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/ihr-hund-ist-willkommen\\\/\",\"url\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/ihr-hund-ist-willkommen\\\/\",\"name\":\"Ihr Hund ist willkommen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/ihr-hund-ist-willkommen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/ihr-hund-ist-willkommen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/05\\\/Pintrip_2021_11-scaled-e1652695943120.jpg\",\"datePublished\":\"2022-05-16T10:13:39+00:00\",\"dateModified\":\"2022-05-16T10:13:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/#\\\/schema\\\/person\\\/784b9d12953c006071a98024f5ae29a5\"},\"description\":\"Bei \u00fcber 90 % unserer Gastgeber ist auch Ihr Hund willkommen. Das Symbol mit dem Hund auf der Gastgeberseite zeigt, dass HIER Ihr Hund willkommen ist. Bei einigen\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/ihr-hund-ist-willkommen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pintrip.eu\\\/de\\\/ihr-hund-ist-willkommen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/ihr-hund-ist-willkommen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/05\\\/Pintrip_2021_11-scaled-e1652695943120.jpg\",\"contentUrl\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/05\\\/Pintrip_2021_11-scaled-e1652695943120.jpg\",\"width\":967,\"height\":990,\"caption\":\"Pintrip-G\u00e4ste sitzen mit Hund auf dem Badepier\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/ihr-hund-ist-willkommen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ihr Hund ist willkommen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/\",\"name\":\"pintrip.eu\\\/de\",\"description\":\"a way of living\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/#\\\/schema\\\/person\\\/784b9d12953c006071a98024f5ae29a5\",\"name\":\"Henriette - Pintrip\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/886176521270c62c5f3ea099223aa87dd8724f2e18252a9b2a3440e95780721e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/886176521270c62c5f3ea099223aa87dd8724f2e18252a9b2a3440e95780721e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/886176521270c62c5f3ea099223aa87dd8724f2e18252a9b2a3440e95780721e?s=96&d=mm&r=g\",\"caption\":\"Henriette - Pintrip\"},\"sameAs\":[\"https:\\\/\\\/pintrip.eu\"],\"url\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/author\\\/pintrip\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ihr Hund ist willkommen","description":"Bei \u00fcber 90 % unserer Gastgeber ist auch Ihr Hund willkommen. Das Symbol mit dem Hund auf der Gastgeberseite zeigt, dass HIER Ihr Hund willkommen ist. Bei einigen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pintrip.eu\/de\/ihr-hund-ist-willkommen\/","og_locale":"de_DE","og_type":"article","og_title":"Ihr Hund ist willkommen","og_description":"Bei \u00fcber 90 % unserer Gastgeber ist auch Ihr Hund willkommen. Das Symbol mit dem Hund auf der Gastgeberseite zeigt, dass HIER Ihr Hund willkommen ist. Bei einigen","og_url":"https:\/\/pintrip.eu\/de\/ihr-hund-ist-willkommen\/","og_site_name":"pintrip.eu\/de","article_published_time":"2022-05-16T10:13:39+00:00","article_modified_time":"2022-05-16T10:13:44+00:00","og_image":[{"width":967,"height":990,"url":"https:\/\/pintrip.eu\/de\/wp-content\/uploads\/sites\/8\/2022\/05\/Pintrip_2021_11-scaled-e1652695943120.jpg","type":"image\/jpeg"}],"author":"Henriette - Pintrip","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Henriette - Pintrip","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pintrip.eu\/de\/ihr-hund-ist-willkommen\/#article","isPartOf":{"@id":"https:\/\/pintrip.eu\/de\/ihr-hund-ist-willkommen\/"},"author":{"name":"Henriette - Pintrip","@id":"https:\/\/pintrip.eu\/de\/#\/schema\/person\/784b9d12953c006071a98024f5ae29a5"},"headline":"Ihr Hund ist willkommen","datePublished":"2022-05-16T10:13:39+00:00","dateModified":"2022-05-16T10:13:44+00:00","mainEntityOfPage":{"@id":"https:\/\/pintrip.eu\/de\/ihr-hund-ist-willkommen\/"},"wordCount":191,"image":{"@id":"https:\/\/pintrip.eu\/de\/ihr-hund-ist-willkommen\/#primaryimage"},"thumbnailUrl":"https:\/\/pintrip.eu\/de\/wp-content\/uploads\/sites\/8\/2022\/05\/Pintrip_2021_11-scaled-e1652695943120.jpg","articleSection":["Blog"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/pintrip.eu\/de\/ihr-hund-ist-willkommen\/","url":"https:\/\/pintrip.eu\/de\/ihr-hund-ist-willkommen\/","name":"Ihr Hund ist willkommen","isPartOf":{"@id":"https:\/\/pintrip.eu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pintrip.eu\/de\/ihr-hund-ist-willkommen\/#primaryimage"},"image":{"@id":"https:\/\/pintrip.eu\/de\/ihr-hund-ist-willkommen\/#primaryimage"},"thumbnailUrl":"https:\/\/pintrip.eu\/de\/wp-content\/uploads\/sites\/8\/2022\/05\/Pintrip_2021_11-scaled-e1652695943120.jpg","datePublished":"2022-05-16T10:13:39+00:00","dateModified":"2022-05-16T10:13:44+00:00","author":{"@id":"https:\/\/pintrip.eu\/de\/#\/schema\/person\/784b9d12953c006071a98024f5ae29a5"},"description":"Bei \u00fcber 90 % unserer Gastgeber ist auch Ihr Hund willkommen. Das Symbol mit dem Hund auf der Gastgeberseite zeigt, dass HIER Ihr Hund willkommen ist. Bei einigen","breadcrumb":{"@id":"https:\/\/pintrip.eu\/de\/ihr-hund-ist-willkommen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pintrip.eu\/de\/ihr-hund-ist-willkommen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/pintrip.eu\/de\/ihr-hund-ist-willkommen\/#primaryimage","url":"https:\/\/pintrip.eu\/de\/wp-content\/uploads\/sites\/8\/2022\/05\/Pintrip_2021_11-scaled-e1652695943120.jpg","contentUrl":"https:\/\/pintrip.eu\/de\/wp-content\/uploads\/sites\/8\/2022\/05\/Pintrip_2021_11-scaled-e1652695943120.jpg","width":967,"height":990,"caption":"Pintrip-G\u00e4ste sitzen mit Hund auf dem Badepier"},{"@type":"BreadcrumbList","@id":"https:\/\/pintrip.eu\/de\/ihr-hund-ist-willkommen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/pintrip.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Ihr Hund ist willkommen"}]},{"@type":"WebSite","@id":"https:\/\/pintrip.eu\/de\/#website","url":"https:\/\/pintrip.eu\/de\/","name":"pintrip.eu\/de","description":"a way of living","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pintrip.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/pintrip.eu\/de\/#\/schema\/person\/784b9d12953c006071a98024f5ae29a5","name":"Henriette - Pintrip","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/886176521270c62c5f3ea099223aa87dd8724f2e18252a9b2a3440e95780721e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/886176521270c62c5f3ea099223aa87dd8724f2e18252a9b2a3440e95780721e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/886176521270c62c5f3ea099223aa87dd8724f2e18252a9b2a3440e95780721e?s=96&d=mm&r=g","caption":"Henriette - Pintrip"},"sameAs":["https:\/\/pintrip.eu"],"url":"https:\/\/pintrip.eu\/de\/author\/pintrip\/"}]}},"_links":{"self":[{"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/posts\/18720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/comments?post=18720"}],"version-history":[{"count":2,"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/posts\/18720\/revisions"}],"predecessor-version":[{"id":18724,"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/posts\/18720\/revisions\/18724"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/media\/18721"}],"wp:attachment":[{"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/media?parent=18720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/categories?post=18720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/tags?post=18720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}