{"id":11625,"date":"2021-08-24T21:06:41","date_gmt":"2021-08-24T20:06:41","guid":{"rendered":"https:\/\/pintrip.eu\/de\/?p=11625"},"modified":"2021-08-25T13:59:38","modified_gmt":"2021-08-25T12:59:38","slug":"gastgeber-werden-im-jahr-2022","status":"publish","type":"post","link":"https:\/\/pintrip.eu\/de\/gastgeber-werden-im-jahr-2022\/","title":{"rendered":"Gastgeber werden im Jahr 2022"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;3.22&#8243;][et_pb_row admin_label=&#8221;row&#8221; _builder_version=&#8221;3.25&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.9.10&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p><strong>Gastgeber werden im Jahr 2022<br \/><\/strong>Obwohl wir erst im August sind, haben wir bereits mit den Vorbereitungen f\u00fcr den Pintrip Guide im n\u00e4chsten Jahr begonnen. Daher suchen wir in allen 13 Kategorien neue Gastgeber f\u00fcr die neue Saison. In diesem Jahr haben wir eine Zunahme der Besuche in der Kategorie &#8220;Stellpl\u00e4tze&#8221; festgestellt, die Orte in einer privateren Umgebung sind, die oft in einer malerischen und ruhigen Umgebung liegen. Wir suchen also noch weitere Gastgeber dieser Art. Wenn Sie also ein gem\u00fctliches Landhaus oder einfach nur einen sch\u00f6nen &#8220;Platz&#8221; haben, den Sie mit anderen Pintrippern teilen m\u00f6chten, w\u00fcrden wir uns freuen, von Ihnen zu h\u00f6ren. Vielleicht kennen Sie auch offensichtlichen Pintrip-Gastgebern in den anderen Kategorien?<\/p>\n<p>Als Pintrip-Gastgeber stellen Sie auf Ihrem Grundst\u00fcck ein bis drei Stellpl\u00e4tze ohne Einrichtungen zur Verf\u00fcgung. Pintrip-G\u00e4ste d\u00fcrfen nur 24 Stunden an deinem Platz bleiben. Es ist v\u00f6llig kostenlos Pintrip-Gastgeber zu sein, da Pintrip f\u00fcr Schilder etc. bezahlt. Selbstverst\u00e4ndlich erhalten Sie auch Ihre ganz pers\u00f6nliche Pintrip-Mitgliedschaft kostenlos dazu. Das Wichtigste ist, dass Sie Zeit und Lust haben, Ihren Platz mit Reisemobilen aus dem In- und Ausland zu teilen. Sind Sie daran interessiert, Pintrip-Gastgeber zu werden, oder kennen Sie einen naheliegenden Ort, rufen wir Sie gerne an und informieren Sie \u00fcber die Vorteile. Sie k\u00f6nnen auch das Registrierungsformular auf unserer Website ausf\u00fcllen. \u00a0Letzter Anmeldeschluss f\u00fcr die Saison 2022 ist der 1. Dezember 2021.<\/p>\n<p>Wir freuen uns von Ihnen zu h\u00f6ren.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gastgeber werden im Jahr 2022Obwohl wir erst im August sind, haben wir bereits mit den Vorbereitungen f\u00fcr den Pintrip Guide im n\u00e4chsten Jahr begonnen. Daher suchen wir in allen 13 Kategorien neue Gastgeber f\u00fcr die neue Saison. In diesem Jahr haben wir eine Zunahme der Besuche in der Kategorie &#8220;Stellpl\u00e4tze&#8221; festgestellt, die Orte in einer [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":11627,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<strong>Die Leute dahinter Pintrip\r\n<\/strong>Wenn Sie 2018 von Anfang an dabei waren, brauchen wir Ihnen wahrscheinlich nicht die gro\u00dfe Pr\u00e4sentation zu machen. Aber wenn Sie seitdem in diesem Universum angekommen sind, sind Sie sich vielleicht nicht ganz sicher, wer wir sind. Die Idee zu Pintrip begann im Sp\u00e4tsommer 2018 und seitdem hat sich viel im Unternehmen getan. Denn ja Pintrip ist ein Unternehmen, keine freiwillige Organisation. Deshalb arbeiten wir nicht gemeinn\u00fctzig. In kurzer Zeit ist viel passiert, daher ist es an der Zeit, uns m\u00f6chten uns kurz bei Ihren vorstellen.\r\n\r\n<strong>Henriette Rask\r\n<\/strong>Inhaber und Gesch\u00e4ftsf\u00fchrer von Pintrip. Im Herbst 2018 verabschiedete sie sich von ihrem Job als Arzthelferin, um sich der Gr\u00fcndungsphase von Pintrip zu widmen \u2013 die sich als zeitaufwendiger herausstellte als gedacht. Henriette ist f\u00fcr das Tagesgesch\u00e4ft von Pintrip verantwortlich und hat verschiedene Funktionen. Wenn Sie also Pintrip anrufen oder schreiben, wird sie antworten. Henriette bleibt mit allen Pintrip-Gastgebern in Kontakt und wei\u00df immer, was im Pintrip-Universum und in der Reisemobilwelt los ist. Au\u00dferdem k\u00fcmmert sie sich um die t\u00e4gliche administrative Arbeit und schreibt gemeinsam mit Nicoline den monatlichen Newsletter und sie liest den Pintrip Guide Korrektur.\r\n\r\n<strong>Peter Rask\r\n<\/strong>Peter ist mit Henriette verheiratet (\u00dcberraschung!). Er ist ein wichtiger Teil des Alltags bei Pintrip, denn er ist ein wichtiger Sparringspartner und der Verpackungsmeister des Unternehmens. Unter anderem ist es Peter, der dir einen Pintrip-Guide gepackt und geschickt hat. Er sorgt daf\u00fcr, dass all die tausenden Pintrip-F\u00fchrer mit Vignetten, Mitgliedskarten und diversen Zusatzbrosch\u00fcren ordentlich verpackt sind. Es erfordert viel Genauigkeit, die Peter bis zur Perfektion beherrscht. Peter hat auch einen Vollzeitjob als Sozialp\u00e4dagoge.\r\n\r\n<strong>Nicoline Hoelgaard\r\n<\/strong>Kommunikationsbeauftragter, der fast seit dem Start von Pintrip bei uns ist. Begonnen hat es mit einem Praktikum im M\u00e4rz 2019, aus dem zun\u00e4chst eine Teilzeitbesch\u00e4ftigung und sp\u00e4ter eine Vollzeitstellebesch\u00e4ftigung wurde. Aufgrund der Corona-Situation ist es nochmals eine Teilzeitbesch\u00e4ftigung. Sie ist f\u00fcr SoMe verantwortlich, und sie erstellt Social Media Inhalten.\r\n\r\nAu\u00dferdem schreibt sie mit Henriette den monatlichen Newsletter und \u00fcbersetzt ihn anschlie\u00dfend ins Englische und Deutsche. Nicoline ist besonders in den Wintermonaten besch\u00e4ftigt, da sie die Hostseiten f\u00fcr den Pintrip Guide schreibt und diese ins Englische und Deutsche \u00fcbersetzt. Nicoline hat auch einen Teilzeitjob als Verk\u00e4uferin.","_et_gb_content_width":"","footnotes":""},"categories":[64],"tags":[],"class_list":["post-11625","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gastgeber werden im Jahr 2022<\/title>\n<meta name=\"description\" content=\"Obwohl wir erst im August sind, haben wir bereits mit den Vorbereitungen f\u00fcr den Pintrip Guide im n\u00e4chsten Jahr begonnen. Daher suchen wir in allen 13 Kategorien n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pintrip.eu\/de\/gastgeber-werden-im-jahr-2022\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gastgeber werden im Jahr 2022\" \/>\n<meta property=\"og:description\" content=\"Obwohl wir erst im August sind, haben wir bereits mit den Vorbereitungen f\u00fcr den Pintrip Guide im n\u00e4chsten Jahr begonnen. Daher suchen wir in allen 13 Kategorien n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pintrip.eu\/de\/gastgeber-werden-im-jahr-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"pintrip.eu\/de\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-24T20:06:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-25T12:59:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pintrip.eu\/de\/wp-content\/uploads\/sites\/8\/2021\/08\/pintrip-billede-1-576x1024.png\" \/>\n\t<meta property=\"og:image:width\" content=\"576\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Henriette - Pintrip\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Henriette - Pintrip\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/gastgeber-werden-im-jahr-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/gastgeber-werden-im-jahr-2022\\\/\"},\"author\":{\"name\":\"Henriette - Pintrip\",\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/#\\\/schema\\\/person\\\/784b9d12953c006071a98024f5ae29a5\"},\"headline\":\"Gastgeber werden im Jahr 2022\",\"datePublished\":\"2021-08-24T20:06:41+00:00\",\"dateModified\":\"2021-08-25T12:59:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/gastgeber-werden-im-jahr-2022\\\/\"},\"wordCount\":325,\"image\":{\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/gastgeber-werden-im-jahr-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2021\\\/08\\\/pintrip-billede-1-e1629835581791.png\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/gastgeber-werden-im-jahr-2022\\\/\",\"url\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/gastgeber-werden-im-jahr-2022\\\/\",\"name\":\"Gastgeber werden im Jahr 2022\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/gastgeber-werden-im-jahr-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/gastgeber-werden-im-jahr-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2021\\\/08\\\/pintrip-billede-1-e1629835581791.png\",\"datePublished\":\"2021-08-24T20:06:41+00:00\",\"dateModified\":\"2021-08-25T12:59:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/#\\\/schema\\\/person\\\/784b9d12953c006071a98024f5ae29a5\"},\"description\":\"Obwohl wir erst im August sind, haben wir bereits mit den Vorbereitungen f\u00fcr den Pintrip Guide im n\u00e4chsten Jahr begonnen. Daher suchen wir in allen 13 Kategorien n\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/gastgeber-werden-im-jahr-2022\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pintrip.eu\\\/de\\\/gastgeber-werden-im-jahr-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/gastgeber-werden-im-jahr-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2021\\\/08\\\/pintrip-billede-1-e1629835581791.png\",\"contentUrl\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2021\\\/08\\\/pintrip-billede-1-e1629835581791.png\",\"width\":750,\"height\":820},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/gastgeber-werden-im-jahr-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gastgeber werden im Jahr 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/\",\"name\":\"pintrip.eu\\\/de\",\"description\":\"a way of living\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/#\\\/schema\\\/person\\\/784b9d12953c006071a98024f5ae29a5\",\"name\":\"Henriette - Pintrip\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/886176521270c62c5f3ea099223aa87dd8724f2e18252a9b2a3440e95780721e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/886176521270c62c5f3ea099223aa87dd8724f2e18252a9b2a3440e95780721e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/886176521270c62c5f3ea099223aa87dd8724f2e18252a9b2a3440e95780721e?s=96&d=mm&r=g\",\"caption\":\"Henriette - Pintrip\"},\"sameAs\":[\"https:\\\/\\\/pintrip.eu\"],\"url\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/author\\\/pintrip\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gastgeber werden im Jahr 2022","description":"Obwohl wir erst im August sind, haben wir bereits mit den Vorbereitungen f\u00fcr den Pintrip Guide im n\u00e4chsten Jahr begonnen. Daher suchen wir in allen 13 Kategorien n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pintrip.eu\/de\/gastgeber-werden-im-jahr-2022\/","og_locale":"de_DE","og_type":"article","og_title":"Gastgeber werden im Jahr 2022","og_description":"Obwohl wir erst im August sind, haben wir bereits mit den Vorbereitungen f\u00fcr den Pintrip Guide im n\u00e4chsten Jahr begonnen. Daher suchen wir in allen 13 Kategorien n","og_url":"https:\/\/pintrip.eu\/de\/gastgeber-werden-im-jahr-2022\/","og_site_name":"pintrip.eu\/de","article_published_time":"2021-08-24T20:06:41+00:00","article_modified_time":"2021-08-25T12:59:38+00:00","og_image":[{"width":576,"height":1024,"url":"https:\/\/pintrip.eu\/de\/wp-content\/uploads\/sites\/8\/2021\/08\/pintrip-billede-1-576x1024.png","type":"image\/png"}],"author":"Henriette - Pintrip","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Henriette - Pintrip","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pintrip.eu\/de\/gastgeber-werden-im-jahr-2022\/#article","isPartOf":{"@id":"https:\/\/pintrip.eu\/de\/gastgeber-werden-im-jahr-2022\/"},"author":{"name":"Henriette - Pintrip","@id":"https:\/\/pintrip.eu\/de\/#\/schema\/person\/784b9d12953c006071a98024f5ae29a5"},"headline":"Gastgeber werden im Jahr 2022","datePublished":"2021-08-24T20:06:41+00:00","dateModified":"2021-08-25T12:59:38+00:00","mainEntityOfPage":{"@id":"https:\/\/pintrip.eu\/de\/gastgeber-werden-im-jahr-2022\/"},"wordCount":325,"image":{"@id":"https:\/\/pintrip.eu\/de\/gastgeber-werden-im-jahr-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/pintrip.eu\/de\/wp-content\/uploads\/sites\/8\/2021\/08\/pintrip-billede-1-e1629835581791.png","articleSection":["Blog"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/pintrip.eu\/de\/gastgeber-werden-im-jahr-2022\/","url":"https:\/\/pintrip.eu\/de\/gastgeber-werden-im-jahr-2022\/","name":"Gastgeber werden im Jahr 2022","isPartOf":{"@id":"https:\/\/pintrip.eu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pintrip.eu\/de\/gastgeber-werden-im-jahr-2022\/#primaryimage"},"image":{"@id":"https:\/\/pintrip.eu\/de\/gastgeber-werden-im-jahr-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/pintrip.eu\/de\/wp-content\/uploads\/sites\/8\/2021\/08\/pintrip-billede-1-e1629835581791.png","datePublished":"2021-08-24T20:06:41+00:00","dateModified":"2021-08-25T12:59:38+00:00","author":{"@id":"https:\/\/pintrip.eu\/de\/#\/schema\/person\/784b9d12953c006071a98024f5ae29a5"},"description":"Obwohl wir erst im August sind, haben wir bereits mit den Vorbereitungen f\u00fcr den Pintrip Guide im n\u00e4chsten Jahr begonnen. Daher suchen wir in allen 13 Kategorien n","breadcrumb":{"@id":"https:\/\/pintrip.eu\/de\/gastgeber-werden-im-jahr-2022\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pintrip.eu\/de\/gastgeber-werden-im-jahr-2022\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/pintrip.eu\/de\/gastgeber-werden-im-jahr-2022\/#primaryimage","url":"https:\/\/pintrip.eu\/de\/wp-content\/uploads\/sites\/8\/2021\/08\/pintrip-billede-1-e1629835581791.png","contentUrl":"https:\/\/pintrip.eu\/de\/wp-content\/uploads\/sites\/8\/2021\/08\/pintrip-billede-1-e1629835581791.png","width":750,"height":820},{"@type":"BreadcrumbList","@id":"https:\/\/pintrip.eu\/de\/gastgeber-werden-im-jahr-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/pintrip.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Gastgeber werden im Jahr 2022"}]},{"@type":"WebSite","@id":"https:\/\/pintrip.eu\/de\/#website","url":"https:\/\/pintrip.eu\/de\/","name":"pintrip.eu\/de","description":"a way of living","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pintrip.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/pintrip.eu\/de\/#\/schema\/person\/784b9d12953c006071a98024f5ae29a5","name":"Henriette - Pintrip","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/886176521270c62c5f3ea099223aa87dd8724f2e18252a9b2a3440e95780721e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/886176521270c62c5f3ea099223aa87dd8724f2e18252a9b2a3440e95780721e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/886176521270c62c5f3ea099223aa87dd8724f2e18252a9b2a3440e95780721e?s=96&d=mm&r=g","caption":"Henriette - Pintrip"},"sameAs":["https:\/\/pintrip.eu"],"url":"https:\/\/pintrip.eu\/de\/author\/pintrip\/"}]}},"_links":{"self":[{"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/posts\/11625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/comments?post=11625"}],"version-history":[{"count":3,"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/posts\/11625\/revisions"}],"predecessor-version":[{"id":11630,"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/posts\/11625\/revisions\/11630"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/media\/11627"}],"wp:attachment":[{"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/media?parent=11625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/categories?post=11625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/tags?post=11625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}