{"id":11639,"date":"2021-08-31T08:56:01","date_gmt":"2021-08-31T07:56:01","guid":{"rendered":"https:\/\/pintrip.eu\/de\/?page_id=11639"},"modified":"2024-11-13T14:19:21","modified_gmt":"2024-11-13T13:19:21","slug":"die-goldenen-regeln","status":"publish","type":"page","link":"https:\/\/pintrip.eu\/de\/die-goldenen-regeln\/","title":{"rendered":"Die Goldenen Regeln"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Die Goldenen\u00a0 Regeln<\/h1>\n<hr style=\"width: 45px; float: left; height: 4px; background: #40614d; border: 0px; margin: 15px 10px 0px 0px;\" \/>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.24.2&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>LIEBE PINTRIP-REISENDE, BITTE RESPEKTIEREN SIE W\u00c4HREND IHRES AUFENTHAL UNBEDINGT DIE FOLGENDE REGELN. DIESE REGELN M\u00dcSSEN SIE KENNEN BEVOR SIE LOSFAHREN.<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.25.0&#8243; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<ol>\n<li><strong>Eine g\u00fcltige Mitgliedschaft ist erforderlich, um das Pintrip-Netzwerk zu nutzen.<\/strong> Das Konzept ist ausschlie\u00dflich f\u00fcr Wohnmobil, Bulli, Wohnwagen und Autos mit Dachzelten.<br \/><span style=\"color: #ffffff;\">..<\/span><\/li>\n<li><strong>Gr\u00fc\u00dfen Sie die Gastgeber sowohl bei der Ankunft als auch bei der Abreise.<\/strong> Zeigen Sie bei der Ankunft Ihre digitaler Pintrip Mitgliedskarte vor.<br \/><span style=\"color: #ffffff;\">.<\/span><\/li>\n<li><strong>Aufenthalt ist jeweils auf 24 Stunden bzw. eine Nacht begrenzt.<br \/><span style=\"color: #ffffff;\">.<\/span><br \/><\/strong><\/li>\n<li><strong>Respektieren Sie die Angaben des Gastgebers.<\/strong> Wenn es kein Symbol f\u00fcr zum Beispiel Toilette, Wasser oder Strom gibt, macht es auch keinen Sinn, danach zu fragen.<br \/><span style=\"color: #ffffff;\">..<\/span><\/li>\n<li><strong>Wir m\u00f6chten Sie ermutigen,<\/strong> Interesse an den Produkten und Dienstleistungen des Gastgebers zu zeigen. Es ist eine gro\u00dfartige M\u00f6glichkeit, sich f\u00fcr eine kostenlose und sichere \u00dcbernachtung zu bedanken. Es besteht selbstverst\u00e4ndlich keine Kaufverpflichtung.<br \/><span style=\"color: #ffffff;\">&#8230;.<\/span><\/li>\n<li><strong>Hunde m\u00fcssen immer an der Leine gef\u00fchrt werden.<\/strong> Bei einige Gastgebern sind Hunde nicht erw\u00fcnscht. Denken Sie daran, das Hunde-Symbol zu \u00fcberpr\u00fcfen!\u00ad<span style=\"color: #ffffff;\">.<br \/>..<\/span><\/li>\n<li><strong>Keine Reservierung m\u00f6glich.<\/strong> Es gilt das Prinzip \u201eWer zuerst kommt, mahlt zuerst\u201c. Kontaktieren Sie den Gastgeber maximal 24 Stunden im Voraus bei telefonischem Wunsch.\u00ad<span style=\"color: #ffffff;\">.<br \/>..<\/span><\/li>\n<li><strong>Achten Sie auf die Ankunftszeit und die geschlossenen Zeiten des Gastgebers.<\/strong> Seien Sie verst\u00e4ndnisvoll, wenn es Ausnahmen gibt, bei denen der Gastgeber Sie nicht empfangen kann.\u00ad<span style=\"color: #ffffff;\">.<br \/>..<\/span><\/li>\n<li><strong>Bevor Sie die Einrichtungen<\/strong> des Gastgebers (Strom, Wasser, Toilette usw.) nutzen, bitten Sie um Erlaubnis und besprechen Sie die Bezahlung.<span style=\"color: #ffffff;\">.<\/span><span style=\"color: #ffffff;\">.<br \/>..<\/span><\/li>\n<li><strong>Bitten Sie um Erlaubnis,<\/strong> bevor Sie Tieren klappern oder f\u00fcttern, Lagerfeuer machen, Campingausr\u00fcstung aufstellen usw. Respektieren Sie auch den privaten Bereich des Gastgebers.<span style=\"color: #ffffff;\">..<br \/>..<\/span><\/li>\n<li><strong>Hinterlassen Sie einen sauberen Stellplatz.<\/strong> Entsorgen Sie keinen M\u00fcll, es sei denn, der Gastgeber es erlaubt. Entleeren Sie keine Toilettenkassetten in privaten Toiletten! Die Pintrip-App werden Sie zu den kostenlosen Entsorgungsstationen des Nationalen Stra\u00dfenverwaltung f\u00fchren.<\/li>\n<\/ol>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Goldenen\u00a0 Regeln &nbsp;LIEBE PINTRIP-REISENDE, BITTE RESPEKTIEREN SIE W\u00c4HREND IHRES AUFENTHAL UNBEDINGT DIE FOLGENDE REGELN. DIESE REGELN M\u00dcSSEN SIE KENNEN BEVOR SIE LOSFAHREN. Eine g\u00fcltige Mitgliedschaft ist erforderlich, um das Pintrip-Netzwerk zu nutzen. Das Konzept ist ausschlie\u00dflich f\u00fcr Wohnmobil, Bulli, Wohnwagen und Autos mit Dachzelten&#8230; Gr\u00fc\u00dfen Sie die Gastgeber sowohl bei der Ankunft als auch [&hellip;]<\/p>\n","protected":false},"author":2930,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p><strong>Der Pintrip Guide bietet Zugang zu Stellpl\u00e4tzen im ganzen Land, wo den Gastgebern begr\u00fc\u00dfen Sie und Ihr Wohnmobil einen sicheren Stellplatz f\u00fcr der Nacht zu parken. Es kostet nichts. Das Einzige, was die Gastgeber f\u00fcr Ihnen erwartet, ist, dass Sie die Regeln nachstehend befolgen. Dies stellt sicher, dass beide Gastgeber und G\u00e4sten die besten Erfahrungen haben.<\/strong><\/p><hr \/><ol><li>Nur g\u00fcltige Mitglieder d\u00fcrfen die Pintrip-Stellpl\u00e4tze n\u00fctzen. Befestigen Sie stets Ihre Jahres-Vignette in der Windschutzscheibe.<\/li><li>Kostenlose \u00dcbernachtungen, aber immer mit Respekt f\u00fcr das Privatleben der Gastgeber, weil deren privat Residenz oft neben dem Stellplatz liegt.<\/li><li>Bitte respektieren sie die Ankunfts- zeiten und geschlossene Perioden f\u00fcr G\u00e4ste.<\/li><li>Konsultieren Sie bitte ihren Gastgeber bei Anfahrt und zeigen sie ihm ihre Mitgliedskarte. Sagen Sie bitte auch sch\u00f6n Auf Wiedersehen, wenn sie wieder abreisen.<\/li><li>Zeigen sie gern Interesse f\u00fcr die Produkte ihres Gastgebers, dies ist eine sch\u00f6ne Art und Weise Danke f\u00fcr ein gutes Erlebnis und eine sichere \u00dcbernachtung zu sagen.<\/li><li>Es kann vorkommen dass ihre Gastgeber aus pers\u00f6nlichen oder beruflichen Gr\u00fcnden nicht G\u00e4ste am gew\u00e4hlten Tag empfangen k\u00f6nnen.<\/li><li>Hunde m\u00fcssen immer in einer Leine gehen und sind an manchen Orten gar nicht willkommen.<\/li><li>Merken Sie sich bitte auch, dass einige Leistungen nur gegen eine kleine Bezahlung erh\u00e4ltlich sind. Der Standard der Fazili- t\u00e4ten kann von Ort zu Ort variieren und als Ausgangspunkt m\u00fcssen Sie immer ihre eigene Toilette im Wohnmobil benutzen.<\/li><li>Es ist streng verboten die Toiletten Kassetten in privaten Toiletten zu lehren, die Pintrip App zeigt ihnen den Weg zu den sanit\u00e4ren Anlagen, die sie daf\u00fcr brauchen d\u00fcrfen ist Hinten im Reisef\u00fchrer finden.<\/li><\/ol>","_et_gb_content_width":"","footnotes":""},"class_list":["post-11639","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Goldenen Regeln - pintrip.eu\/de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pintrip.eu\/de\/die-goldenen-regeln\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Goldenen Regeln - pintrip.eu\/de\" \/>\n<meta property=\"og:description\" content=\"Die Goldenen\u00a0 Regeln &nbsp;LIEBE PINTRIP-REISENDE, BITTE RESPEKTIEREN SIE W\u00c4HREND IHRES AUFENTHAL UNBEDINGT DIE FOLGENDE REGELN. DIESE REGELN M\u00dcSSEN SIE KENNEN BEVOR SIE LOSFAHREN. Eine g\u00fcltige Mitgliedschaft ist erforderlich, um das Pintrip-Netzwerk zu nutzen. Das Konzept ist ausschlie\u00dflich f\u00fcr Wohnmobil, Bulli, Wohnwagen und Autos mit Dachzelten... Gr\u00fc\u00dfen Sie die Gastgeber sowohl bei der Ankunft als auch [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pintrip.eu\/de\/die-goldenen-regeln\/\" \/>\n<meta property=\"og:site_name\" content=\"pintrip.eu\/de\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-13T13:19:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pintrip.eu\/de\/wp-content\/uploads\/sites\/8\/2020\/04\/Pintrip_2020-11.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"306\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/die-goldenen-regeln\\\/\",\"url\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/die-goldenen-regeln\\\/\",\"name\":\"Die Goldenen Regeln - pintrip.eu\\\/de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/#website\"},\"datePublished\":\"2021-08-31T07:56:01+00:00\",\"dateModified\":\"2024-11-13T13:19:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/die-goldenen-regeln\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pintrip.eu\\\/de\\\/die-goldenen-regeln\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/die-goldenen-regeln\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Goldenen Regeln\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/\",\"name\":\"pintrip.eu\\\/de\",\"description\":\"a way of living\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pintrip.eu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Goldenen Regeln - pintrip.eu\/de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pintrip.eu\/de\/die-goldenen-regeln\/","og_locale":"de_DE","og_type":"article","og_title":"Die Goldenen Regeln - pintrip.eu\/de","og_description":"Die Goldenen\u00a0 Regeln &nbsp;LIEBE PINTRIP-REISENDE, BITTE RESPEKTIEREN SIE W\u00c4HREND IHRES AUFENTHAL UNBEDINGT DIE FOLGENDE REGELN. DIESE REGELN M\u00dcSSEN SIE KENNEN BEVOR SIE LOSFAHREN. Eine g\u00fcltige Mitgliedschaft ist erforderlich, um das Pintrip-Netzwerk zu nutzen. Das Konzept ist ausschlie\u00dflich f\u00fcr Wohnmobil, Bulli, Wohnwagen und Autos mit Dachzelten... Gr\u00fc\u00dfen Sie die Gastgeber sowohl bei der Ankunft als auch [&hellip;]","og_url":"https:\/\/pintrip.eu\/de\/die-goldenen-regeln\/","og_site_name":"pintrip.eu\/de","article_modified_time":"2024-11-13T13:19:21+00:00","og_image":[{"width":460,"height":306,"url":"https:\/\/pintrip.eu\/de\/wp-content\/uploads\/sites\/8\/2020\/04\/Pintrip_2020-11.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pintrip.eu\/de\/die-goldenen-regeln\/","url":"https:\/\/pintrip.eu\/de\/die-goldenen-regeln\/","name":"Die Goldenen Regeln - pintrip.eu\/de","isPartOf":{"@id":"https:\/\/pintrip.eu\/de\/#website"},"datePublished":"2021-08-31T07:56:01+00:00","dateModified":"2024-11-13T13:19:21+00:00","breadcrumb":{"@id":"https:\/\/pintrip.eu\/de\/die-goldenen-regeln\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pintrip.eu\/de\/die-goldenen-regeln\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/pintrip.eu\/de\/die-goldenen-regeln\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/pintrip.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Die Goldenen Regeln"}]},{"@type":"WebSite","@id":"https:\/\/pintrip.eu\/de\/#website","url":"https:\/\/pintrip.eu\/de\/","name":"pintrip.eu\/de","description":"a way of living","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pintrip.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/pages\/11639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/users\/2930"}],"replies":[{"embeddable":true,"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/comments?post=11639"}],"version-history":[{"count":6,"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/pages\/11639\/revisions"}],"predecessor-version":[{"id":24431,"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/pages\/11639\/revisions\/24431"}],"wp:attachment":[{"href":"https:\/\/pintrip.eu\/de\/wp-json\/wp\/v2\/media?parent=11639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}